{"id":504,"count":0,"description":"","link":"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/","name":"Steel and Accessories","slug":"steel-and-accessories","taxonomy":"products-category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europanels Steel and Accessories - Europanels<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europanels Steel and Accessories - Europanels\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/\" \/>\n<meta property=\"og:site_name\" content=\"Europanels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/products\\\/steel-and-accessories\\\/\",\"url\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/products\\\/steel-and-accessories\\\/\",\"name\":\"Europanels Steel and Accessories - Europanels\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/products\\\/steel-and-accessories\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/products\\\/steel-and-accessories\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steel and Accessories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/\",\"name\":\"Europanels\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/#organization\",\"name\":\"Europanels\",\"url\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.europanels.pl\\\/new-content\\\/uploads\\\/2024\\\/11\\\/Group-51.svg\",\"contentUrl\":\"https:\\\/\\\/www.europanels.pl\\\/new-content\\\/uploads\\\/2024\\\/11\\\/Group-51.svg\",\"caption\":\"Europanels\"},\"image\":{\"@id\":\"https:\\\/\\\/www.europanels.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europanels Steel and Accessories - Europanels","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/","og_locale":"en_US","og_type":"article","og_title":"Europanels Steel and Accessories - Europanels","og_url":"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/","og_site_name":"Europanels","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/","url":"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/","name":"Europanels Steel and Accessories - Europanels","isPartOf":{"@id":"https:\/\/www.europanels.pl\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.europanels.pl\/en\/products\/steel-and-accessories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.europanels.pl\/en\/"},{"@type":"ListItem","position":2,"name":"Steel and Accessories"}]},{"@type":"WebSite","@id":"https:\/\/www.europanels.pl\/en\/#website","url":"https:\/\/www.europanels.pl\/en\/","name":"Europanels","description":"","publisher":{"@id":"https:\/\/www.europanels.pl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.europanels.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.europanels.pl\/en\/#organization","name":"Europanels","url":"https:\/\/www.europanels.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.europanels.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.europanels.pl\/new-content\/uploads\/2024\/11\/Group-51.svg","contentUrl":"https:\/\/www.europanels.pl\/new-content\/uploads\/2024\/11\/Group-51.svg","caption":"Europanels"},"image":{"@id":"https:\/\/www.europanels.pl\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.europanels.pl\/en\/wp-json\/wp\/v2\/products-category\/504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europanels.pl\/en\/wp-json\/wp\/v2\/products-category"}],"about":[{"href":"https:\/\/www.europanels.pl\/en\/wp-json\/wp\/v2\/taxonomies\/products-category"}]}}